{"id":150939,"date":"2026-03-25T09:12:16","date_gmt":"2026-03-25T09:12:16","guid":{"rendered":"https:\/\/clece.es\/?p=150939"},"modified":"2026-03-25T09:12:17","modified_gmt":"2026-03-25T09:12:17","slug":"clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo","status":"publish","type":"post","link":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/","title":{"rendered":"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Esta nueva entrega de <strong>Clece te informa<\/strong> se centra en nuestra filial <strong>Integra<\/strong>, el centro especial de empleo de iniciativa empresarial m\u00e1s grande de Espa\u00f1a que cuenta con una plantilla de m\u00e1s de 6.300 profesionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Luis Cruz<\/strong>, director de Integra CEE, y <strong>Mayte Barroso<\/strong>, t\u00e9cnica de una de sus unidades de apoyo, explican las claves del modelo de gesti\u00f3n social con el que la compa\u00f1\u00eda impulsa la integraci\u00f3n sociolaboral de personas con discapacidad.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Clece te informa #7\" src=\"https:\/\/player.vimeo.com\/video\/1176514850?dnt=1&amp;app_id=122963\" width=\"800\" height=\"450\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Esta nueva entrega de Clece te informa se centra en nuestra filial Integra, el centro especial de empleo de iniciativa empresarial m\u00e1s grande de Espa\u00f1a que cuenta con una plantilla de m\u00e1s de 6.300 profesionales. Luis Cruz, director de Integra CEE, y Mayte Barroso, t\u00e9cnica de una de sus unidades de apoyo, explican las claves [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":150949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[33,1],"tags":[291],"class_list":["post-150939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-sin-categorizar","tag-destacado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo - Clece<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo - Clece\" \/>\n<meta property=\"og:description\" content=\"Esta nueva entrega de Clece te informa se centra en nuestra filial Integra, el centro especial de empleo de iniciativa empresarial m\u00e1s grande de Espa\u00f1a que cuenta con una plantilla de m\u00e1s de 6.300 profesionales. Luis Cruz, director de Integra CEE, y Mayte Barroso, t\u00e9cnica de una de sus unidades de apoyo, explican las claves [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/\" \/>\n<meta property=\"og:site_name\" content=\"Clece\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CleceSociedadAnonima\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T09:12:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T09:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/clece.es\/wp-content\/uploads\/2026\/03\/Cleceinforma-Integra-web-1200x750-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mar Rodr\u00edguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Clece_\" \/>\n<meta name=\"twitter:site\" content=\"@Clece_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/\"},\"author\":{\"name\":\"Mar Rodr\u00edguez\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#\\\/schema\\\/person\\\/cd5d6e7d77bb6f448e4abc974139118e\"},\"headline\":\"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo\",\"datePublished\":\"2026-03-25T09:12:16+00:00\",\"dateModified\":\"2026-03-25T09:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/\"},\"wordCount\":96,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clece.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cleceinforma-Integra-web-1200x750-2.jpg\",\"keywords\":[\"destacado\"],\"articleSection\":[\"Noticias\",\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/\",\"url\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/\",\"name\":\"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo - Clece\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/clece.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cleceinforma-Integra-web-1200x750-2.jpg\",\"datePublished\":\"2026-03-25T09:12:16+00:00\",\"dateModified\":\"2026-03-25T09:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/clece.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cleceinforma-Integra-web-1200x750-2.jpg\",\"contentUrl\":\"https:\\\/\\\/clece.es\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Cleceinforma-Integra-web-1200x750-2.jpg\",\"width\":1200,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/2026\\\/03\\\/25\\\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/clece.es\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/clece.es\\\/es\\\/\",\"name\":\"Clece\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/clece.es\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#organization\",\"name\":\"Grupo Clece\",\"url\":\"https:\\\/\\\/clece.es\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sitio2.utopiasl.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logotipos_filiales_Clece_logotipo.png\",\"contentUrl\":\"https:\\\/\\\/sitio2.utopiasl.eu\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logotipos_filiales_Clece_logotipo.png\",\"width\":5000,\"height\":5000,\"caption\":\"Grupo Clece\"},\"image\":{\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CleceSociedadAnonima\\\/\",\"https:\\\/\\\/x.com\\\/Clece_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/clece-sa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/clece.es\\\/es\\\/#\\\/schema\\\/person\\\/cd5d6e7d77bb6f448e4abc974139118e\",\"name\":\"Mar Rodr\u00edguez\",\"url\":\"https:\\\/\\\/clece.es\\\/es\\\/author\\\/mrodriguezse\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo - Clece","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/","og_locale":"es_ES","og_type":"article","og_title":"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo - Clece","og_description":"Esta nueva entrega de Clece te informa se centra en nuestra filial Integra, el centro especial de empleo de iniciativa empresarial m\u00e1s grande de Espa\u00f1a que cuenta con una plantilla de m\u00e1s de 6.300 profesionales. Luis Cruz, director de Integra CEE, y Mayte Barroso, t\u00e9cnica de una de sus unidades de apoyo, explican las claves [&hellip;]","og_url":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/","og_site_name":"Clece","article_publisher":"https:\/\/www.facebook.com\/CleceSociedadAnonima\/","article_published_time":"2026-03-25T09:12:16+00:00","article_modified_time":"2026-03-25T09:12:17+00:00","og_image":[{"width":1200,"height":750,"url":"https:\/\/clece.es\/wp-content\/uploads\/2026\/03\/Cleceinforma-Integra-web-1200x750-2.jpg","type":"image\/jpeg"}],"author":"Mar Rodr\u00edguez","twitter_card":"summary_large_image","twitter_creator":"@Clece_","twitter_site":"@Clece_","twitter_misc":{"Escrito por":"Mar Rodr\u00edguez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#article","isPartOf":{"@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/"},"author":{"name":"Mar Rodr\u00edguez","@id":"https:\/\/clece.es\/es\/#\/schema\/person\/cd5d6e7d77bb6f448e4abc974139118e"},"headline":"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo","datePublished":"2026-03-25T09:12:16+00:00","dateModified":"2026-03-25T09:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/"},"wordCount":96,"commentCount":1,"publisher":{"@id":"https:\/\/clece.es\/es\/#organization"},"image":{"@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#primaryimage"},"thumbnailUrl":"https:\/\/clece.es\/wp-content\/uploads\/2026\/03\/Cleceinforma-Integra-web-1200x750-2.jpg","keywords":["destacado"],"articleSection":["Noticias","Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/","url":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/","name":"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo - Clece","isPartOf":{"@id":"https:\/\/clece.es\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#primaryimage"},"image":{"@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#primaryimage"},"thumbnailUrl":"https:\/\/clece.es\/wp-content\/uploads\/2026\/03\/Cleceinforma-Integra-web-1200x750-2.jpg","datePublished":"2026-03-25T09:12:16+00:00","dateModified":"2026-03-25T09:12:17+00:00","breadcrumb":{"@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#primaryimage","url":"https:\/\/clece.es\/wp-content\/uploads\/2026\/03\/Cleceinforma-Integra-web-1200x750-2.jpg","contentUrl":"https:\/\/clece.es\/wp-content\/uploads\/2026\/03\/Cleceinforma-Integra-web-1200x750-2.jpg","width":1200,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/clece.es\/es\/2026\/03\/25\/clece-te-informa-marzo-de-2026-las-claves-de-integra-nuestro-centro-especial-de-empleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/clece.es\/es\/"},{"@type":"ListItem","position":2,"name":"Clece te informa: Marzo de 2026 |\u00a0Las claves de Integra, nuestro centro especial de empleo"}]},{"@type":"WebSite","@id":"https:\/\/clece.es\/es\/#website","url":"https:\/\/clece.es\/es\/","name":"Clece","description":"","publisher":{"@id":"https:\/\/clece.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/clece.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/clece.es\/es\/#organization","name":"Grupo Clece","url":"https:\/\/clece.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/clece.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sitio2.utopiasl.eu\/wp-content\/uploads\/2024\/10\/Logotipos_filiales_Clece_logotipo.png","contentUrl":"https:\/\/sitio2.utopiasl.eu\/wp-content\/uploads\/2024\/10\/Logotipos_filiales_Clece_logotipo.png","width":5000,"height":5000,"caption":"Grupo Clece"},"image":{"@id":"https:\/\/clece.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CleceSociedadAnonima\/","https:\/\/x.com\/Clece_","https:\/\/www.linkedin.com\/company\/clece-sa\/"]},{"@type":"Person","@id":"https:\/\/clece.es\/es\/#\/schema\/person\/cd5d6e7d77bb6f448e4abc974139118e","name":"Mar Rodr\u00edguez","url":"https:\/\/clece.es\/es\/author\/mrodriguezse\/"}]}},"_links":{"self":[{"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/posts\/150939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/comments?post=150939"}],"version-history":[{"count":2,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/posts\/150939\/revisions"}],"predecessor-version":[{"id":150947,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/posts\/150939\/revisions\/150947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/media\/150949"}],"wp:attachment":[{"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/media?parent=150939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/categories?post=150939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clece.es\/es\/wp-json\/wp\/v2\/tags?post=150939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}